{"id":98001,"date":"2024-08-06T08:09:23","date_gmt":"2024-08-06T14:09:23","guid":{"rendered":"https:\/\/amanecerhuasteco.com\/portal\/?p=98001"},"modified":"2024-08-06T08:24:31","modified_gmt":"2024-08-06T14:24:31","slug":"ejecutivo-inicia-instalacion-de-comites-sociales-de-obras","status":"publish","type":"post","link":"https:\/\/amanecerhuasteco.com\/portal\/ejecutivo-inicia-instalacion-de-comites-sociales-de-obras\/","title":{"rendered":"Ejecutivo inicia instalaci\u00f3n de comit\u00e9s sociales de obras"},"content":{"rendered":"\n<p><br>\u2022 Habitantes de la comunidad La Ventilla, en Villa de Reyes, agradecieron al Gobernador Ricardo Gallardo Cardona por ser tomados en cuenta al escuchar las necesidades<\/p>\n\n\n\n<p>La Secretar\u00eda de Desarrollo Social y Regional (Sedesore), inici\u00f3 la instalaci\u00f3n de los Comit\u00e9s Sociales de Obras, en la comunidad de la Ventilla, en Villa de Reyes, donde las y los habitantes tendr\u00e1n voz y ser\u00e1n part\u00edcipes en los proyectos que se realicen, en apoyo a una mejor calidad de vida y bienestar.<br>En cumplimiento a la instrucci\u00f3n del Gobernador Ricardo Gallardo Cardona de atender las necesidades de las familias potosinas, la titular de Sedesore Mar\u00eda del Rosario Mart\u00ednez Galarza tom\u00f3 protesta al comit\u00e9 instalado, para la construcci\u00f3n del camino del Entronque Carretero Villa de Reyes-Bledos, obra que ser\u00e1 de gran ayuda, pues les permitir\u00e1 mayor conectividad con otras comunidades, as\u00ed como tener la certeza en calidad de esta obra de infraestructura social.<br>Las y los asistentes mostraron su agradecimiento con el Gobernador del Estado por ser tomados en cuenta al escuchar las necesidades de esta mientras que la titular de la Sedesore destac\u00f3 que, as\u00ed como en esta comunidad se busca formar los comit\u00e9s en las cuatro regiones de San Luis Potos\u00ed, y se estar\u00e1 en continua gira de trabajo para su conformarlos.<br>Tomaron protesta Gregorio Flores Ram\u00edrez como Contralor social; Santiago Mart\u00ednez Rivas como responsable de preliminares; Ernesto Gonz\u00e1lez Garc\u00eda como responsable de terracer\u00edas; Francisco Rojas Gonz\u00e1lez, responsable de drenaje; Jos\u00e9 Dolores Mart\u00ednez Garc\u00eda, responsable de se\u00f1alamiento; y Mar\u00eda Guadalupe Rochas Rivas como responsable de varios de la obra.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u2022 Habitantes de la comunidad La Ventilla, en Villa de Reyes, agradecieron al Gobernador Ricardo Gallardo Cardona por ser tomados en cuenta al escuchar las necesidades La Secretar\u00eda de Desarrollo Social y Regional (Sedesore), inici\u00f3 la instalaci\u00f3n de los Comit\u00e9s Sociales de Obras, en la &hellip; <\/p>\n","protected":false},"author":1,"featured_media":98002,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[25,7,22,56,11,55,4,44,5,60,30,31,59,42,21,53,20,57,43,32],"tags":[],"class_list":["post-98001","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-aquismon","category-ciudad","category-ebano","category-el-naranjo","category-estado","category-guadalcazar","category-inicio","category-matehuala","category-politica","category-rayon","category-rioverde","category-sanluispotosi","category-santa-catarina","category-soledad","category-tamasopo","category-tamazunchale","category-tamuin","category-tanlajas","category-villa-de-reyes","category-xilitla"],"_links":{"self":[{"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/posts\/98001","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/comments?post=98001"}],"version-history":[{"count":1,"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/posts\/98001\/revisions"}],"predecessor-version":[{"id":98003,"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/posts\/98001\/revisions\/98003"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/media\/98002"}],"wp:attachment":[{"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/media?parent=98001"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/categories?post=98001"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/tags?post=98001"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}