{"id":99165,"date":"2024-09-11T08:12:26","date_gmt":"2024-09-11T14:12:26","guid":{"rendered":"https:\/\/amanecerhuasteco.com\/portal\/?p=99165"},"modified":"2024-09-11T08:12:27","modified_gmt":"2024-09-11T14:12:27","slug":"ejecutivo-estatal-con-operativo-listo-por-fiestas-patrias-2024","status":"publish","type":"post","link":"https:\/\/amanecerhuasteco.com\/portal\/ejecutivo-estatal-con-operativo-listo-por-fiestas-patrias-2024\/","title":{"rendered":"Ejecutivo Estatal con operativo listo por fiestas patrias 2024"},"content":{"rendered":"\n<p><br>\u2022 Elementos estatales, en coordinaci\u00f3n con los 59 ayuntamientos, vigilar\u00e1n zonas de mayor afluencia y carreteras por el aniversario de la promulgaci\u00f3n de la Independencia de M\u00e9xico<\/p>\n\n\n\n<p>El Gobierno del Estado, en coordinaci\u00f3n interinstitucional, aplicar\u00e1 el Plan General de Acci\u00f3n para garantizar la seguridad durante la conmemoraci\u00f3n de las Fiestas Patrias 2024, en el que participar\u00e1n corporaciones municipales, estatales y federales, as\u00ed como cuerpos de rescate y auxilio y de otras \u00e1reas como la Direcci\u00f3n de Gobernaci\u00f3n, para prevenir y atender cualquier incidente que ponga en riesgo a las y los asistentes a estos festejos.<br>El secretario general de Gobierno, J. Guadalupe Torres S\u00e1nchez, inform\u00f3 que la indicaci\u00f3n del Gobernador Ricardo Gallardo Cardona es que las \u00e1reas de seguridad y vigilancia est\u00e9n atentas el 15 de septiembre para garantizar a las y los potosinos y turistas que habr\u00e1 un entorno seguro, con orden y vigilancia para que las familias disfruten, \u201cporque hay voluntad y compromiso en esta celebraci\u00f3n y que se refleje la uni\u00f3n, la democracia y la transformaci\u00f3n social del pa\u00eds\u201d, agreg\u00f3.<br>Torres S\u00e1nchez a\u00f1adi\u00f3 que el despliegue operativo en los 59 ayuntamientos iniciar\u00e1 a las 6:00 horas del 12 de septiembre con vigilancia de las y los elementos de seguridad, monitoreo con las c\u00e1maras de vigilancia del C5i2 y veh\u00edculos para los recorridos en las carreteras estatales, tras resaltar a trav\u00e9s de la Subsecretar\u00eda de Gobernaci\u00f3n mantiene el di\u00e1logo con comerciantes y establecimientos para supervisar sus operaciones y que contribuyan al orden del evento.<br>El secretario general de Gobierno precis\u00f3 que no hay registro de focos rojos en los municipios; sin embargo, fortalecer\u00e1n los operativos en los municipios de mayor concentraci\u00f3n de poblaci\u00f3n como la capital potosina, Soledad de Graciano S\u00e1nchez, Ciudad Valles, Rioverde, Matehuala, Tamazunchale y Xilitla, con recorridos de vigilancia y presencia municipal, estatal y federal.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u2022 Elementos estatales, en coordinaci\u00f3n con los 59 ayuntamientos, vigilar\u00e1n zonas de mayor afluencia y carreteras por el aniversario de la promulgaci\u00f3n de la Independencia de M\u00e9xico El Gobierno del Estado, en coordinaci\u00f3n interinstitucional, aplicar\u00e1 el Plan General de Acci\u00f3n para garantizar la seguridad durante &hellip; <\/p>\n","protected":false},"author":1,"featured_media":99166,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[25,7,63,22,56,11,55,4,44,26,10,12,60,30,31,59,42,21,53,20,57,43,32],"tags":[],"class_list":["post-99165","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-aquismon","category-ciudad","category-coxcatlan","category-ebano","category-el-naranjo","category-estado","category-guadalcazar","category-inicio","category-matehuala","category-matlapa","category-municipios","category-nacional","category-rayon","category-rioverde","category-sanluispotosi","category-santa-catarina","category-soledad","category-tamasopo","category-tamazunchale","category-tamuin","category-tanlajas","category-villa-de-reyes","category-xilitla"],"_links":{"self":[{"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/posts\/99165","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/comments?post=99165"}],"version-history":[{"count":1,"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/posts\/99165\/revisions"}],"predecessor-version":[{"id":99167,"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/posts\/99165\/revisions\/99167"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/media\/99166"}],"wp:attachment":[{"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/media?parent=99165"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/categories?post=99165"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/tags?post=99165"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}